{"id":191,"date":"2025-04-13T22:48:57","date_gmt":"2025-04-14T01:48:57","guid":{"rendered":"https:\/\/latinaradio.cl\/?p=191"},"modified":"2025-04-13T22:48:57","modified_gmt":"2025-04-14T01:48:57","slug":"vina-del-mar-celebro-a-lo-grande-con-la-caminata-familiar-canina","status":"publish","type":"post","link":"https:\/\/latinaradio.cl\/index.php\/2025\/04\/13\/vina-del-mar-celebro-a-lo-grande-con-la-caminata-familiar-canina\/","title":{"rendered":"Vi\u00f1a del Mar celebr\u00f3 a lo grande con la Caminata Familiar Canina"},"content":{"rendered":"<p class=\"\" data-start=\"183\" data-end=\"628\">Este <strong data-start=\"188\" data-end=\"211\">domingo 13 de abril<\/strong>, Vi\u00f1a del Mar se llen\u00f3 de alegr\u00eda, deporte y compa\u00f1erismo con la realizaci\u00f3n de la <strong data-start=\"295\" data-end=\"323\">Caminata Familiar Canina<\/strong>, una actividad organizada por <strong data-start=\"354\" data-end=\"378\">Carabineros de Chile<\/strong> y patrocinada por el <strong data-start=\"400\" data-end=\"419\">municipio local<\/strong>. Desde temprano, miles de vecinos y vecinas llegaron hasta <strong data-start=\"479\" data-end=\"496\">Caleta Abarca<\/strong> junto a sus perritos, listos para participar en este recorrido de <strong data-start=\"563\" data-end=\"579\">3 kil\u00f3metros<\/strong> pensado especialmente para disfrutar en familia.<\/p>\n<p class=\"\" data-start=\"630\" data-end=\"1081\">La jornada comenz\u00f3 a las <strong data-start=\"655\" data-end=\"670\">09:00 horas<\/strong> y se extendi\u00f3 por alrededor de <strong data-start=\"702\" data-end=\"717\">cinco horas<\/strong>, en las que no faltaron los momentos emotivos, las muestras de cari\u00f1o entre humanos y mascotas, y un ambiente de total tranquilidad y camarader\u00eda. La caminata no solo fue una instancia recreativa, sino que tambi\u00e9n sirvi\u00f3 para conmemorar el <strong data-start=\"958\" data-end=\"992\">98\u00b0 aniversario de Carabineros<\/strong>, con un enfoque en <strong data-start=\"1012\" data-end=\"1080\">valores como la vida saludable, el deporte y el bienestar animal<\/strong>.<\/p>\n<p class=\"\" data-start=\"1083\" data-end=\"1203\">La <strong data-start=\"1086\" data-end=\"1118\">alcaldesa Macarena Ripamonti<\/strong> estuvo presente en el evento y destac\u00f3 la importancia de este tipo de iniciativas.<\/p>\n<blockquote data-start=\"1204\" data-end=\"1459\">\n<p class=\"\" data-start=\"1206\" data-end=\"1459\">\u201cDesde el Municipio de Vi\u00f1a del Mar es un orgullo colaborar con Carabineros en la Caminata Canina Familiar\u201d, se\u00f1al\u00f3 la jefa comunal, agregando que<br data-start=\"1352\" data-end=\"1355\">\u201cesta actividad tiene como objetivo fortalecer los lazos entre la comunidad y nuestras instituciones\u201d.<\/p>\n<\/blockquote>\n<p class=\"\" data-start=\"1461\" data-end=\"1640\">Adem\u00e1s, la alcaldesa enfatiz\u00f3 que Vi\u00f1a del Mar busca consolidarse como una ciudad <strong data-start=\"1543\" data-end=\"1585\">activa, inclusiva y cercana a su gente<\/strong>, y que actividades como esta refuerzan ese compromiso.<\/p>\n<p class=\"\" data-start=\"1642\" data-end=\"1988\">Durante la caminata tambi\u00e9n se realizaron charlas informativas, exhibiciones y actividades educativas sobre el cuidado responsable de mascotas. Participaron agrupaciones animalistas, unidades caninas de Carabineros y distintos servicios municipales, quienes ofrecieron orientaci\u00f3n y servicios gratuitos como control veterinario y desparasitaci\u00f3n.<\/p>\n<p class=\"\" data-start=\"1990\" data-end=\"2311\">Vecinos y vecinas valoraron positivamente la instancia, destacando el ambiente seguro, el buen \u00e1nimo de los participantes y la oportunidad de compartir con otros amantes de los animales. Muchos llegaron con sus mascotas ataviadas con pa\u00f1uelos verdes, disfraces y bandanas, haciendo a\u00fan m\u00e1s colorida esta ma\u00f1ana dominical.<\/p>\n<p class=\"\" data-start=\"2313\" data-end=\"2507\">La Caminata Familiar Canina se perfila como una actividad que podr\u00eda repetirse a\u00f1o a a\u00f1o, fortaleciendo el v\u00ednculo entre la comunidad, las instituciones y nuestros queridos animales de compa\u00f1\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este domingo 13 de abril, Vi\u00f1a del Mar se llen\u00f3 de alegr\u00eda, deporte y compa\u00f1erismo con la realizaci\u00f3n de la Caminata Familiar Canina, una actividad organizada por Carabineros de Chile y patrocinada por el municipio local. Desde temprano, miles de vecinos y vecinas llegaron hasta Caleta Abarca junto a sus perritos, listos para participar en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":192,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/191"}],"collection":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/comments?post=191"}],"version-history":[{"count":1,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/191\/revisions"}],"predecessor-version":[{"id":193,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/191\/revisions\/193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/media\/192"}],"wp:attachment":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/media?parent=191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/categories?post=191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/tags?post=191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}