{"id":269,"date":"2025-04-23T21:54:47","date_gmt":"2025-04-24T00:54:47","guid":{"rendered":"https:\/\/latinaradio.cl\/?p=269"},"modified":"2025-04-23T21:54:47","modified_gmt":"2025-04-24T00:54:47","slug":"buenas-noticias-desde-el-zoologico-de-quilpue-nacio-un-nuevo-condor","status":"publish","type":"post","link":"https:\/\/latinaradio.cl\/index.php\/2025\/04\/23\/buenas-noticias-desde-el-zoologico-de-quilpue-nacio-un-nuevo-condor\/","title":{"rendered":"Buenas noticias desde el Zool\u00f3gico de Quilpu\u00e9: naci\u00f3 un nuevo c\u00f3ndor"},"content":{"rendered":"<p class=\"\" data-start=\"177\" data-end=\"519\">El Zool\u00f3gico de Quilpu\u00e9 anunci\u00f3 con alegr\u00eda el nacimiento de un c\u00f3ndor andino (<em data-start=\"256\" data-end=\"272\">Vultur gryphus<\/em>), una especie que se encuentra en estado vulnerable de conservaci\u00f3n. Sus padres, que viven en el recinto desde hace m\u00e1s de 20 a\u00f1os tras ser rescatados con lesiones que les impiden volar, lograron empollar exitosamente un huevo en octubre de 2024.<\/p>\n<p class=\"\" data-start=\"521\" data-end=\"738\">\u201cEl pich\u00f3n est\u00e1 sano, no necesita medicamentos y actualmente est\u00e1 siendo monitoreado con chequeos visuales de salud. Se encuentra aislado, pero acompa\u00f1ado por sus padres\u201d, explic\u00f3 Patricio Ruz, director del zool\u00f3gico.<\/p>\n<p class=\"\" data-start=\"740\" data-end=\"996\">Seg\u00fan detall\u00f3, ambos c\u00f3ndores participan activamente en el cuidado del nuevo integrante de la familia, aliment\u00e1ndolo y protegi\u00e9ndolo. Este proceso se extiende entre 12 y 18 meses, aunque el pich\u00f3n comienza a explorar fuera del nido a partir de los 6 meses.<\/p>\n<p class=\"\" data-start=\"998\" data-end=\"1277\">La meta de los expertos es ambiciosa y esperanzadora: si todo marcha bien, el c\u00f3ndor podr\u00eda ser liberado en 2026 en su h\u00e1bitat natural, en la cordillera, acompa\u00f1ado por una bandada y con seguimiento del Servicio Agr\u00edcola y Ganadero (SAG), como parte de un proceso de reinserci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Zool\u00f3gico de Quilpu\u00e9 anunci\u00f3 con alegr\u00eda el nacimiento de un c\u00f3ndor andino (Vultur gryphus), una especie que se encuentra en estado vulnerable de conservaci\u00f3n. Sus padres, que viven en el recinto desde hace m\u00e1s de 20 a\u00f1os tras ser rescatados con lesiones que les impiden volar, lograron empollar exitosamente un huevo en octubre de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":270,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/269"}],"collection":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/comments?post=269"}],"version-history":[{"count":1,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/269\/revisions"}],"predecessor-version":[{"id":271,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/269\/revisions\/271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/media\/270"}],"wp:attachment":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/media?parent=269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/categories?post=269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/tags?post=269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}