{"id":2756,"date":"2025-09-24T14:49:02","date_gmt":"2025-09-24T17:49:02","guid":{"rendered":"https:\/\/latinaradio.cl\/?p=2756"},"modified":"2025-09-24T14:49:02","modified_gmt":"2025-09-24T17:49:02","slug":"pancho-melo-destaca-en-festival-internacional-con-cortometraje-la-matadero-la-carniceria","status":"publish","type":"post","link":"https:\/\/latinaradio.cl\/index.php\/2025\/09\/24\/pancho-melo-destaca-en-festival-internacional-con-cortometraje-la-matadero-la-carniceria\/","title":{"rendered":"Pancho Melo destaca en festival internacional con cortometraje \u201cLa Matadero \u2013 La Carnicer\u00eda\u201d"},"content":{"rendered":"<p data-start=\"228\" data-end=\"422\">El actor chileno Pancho Melo suma un nuevo reconocimiento internacional gracias a su participaci\u00f3n en el cortometraje \u201cLa Matadero \u2013 La Carnicer\u00eda\u201d, dirigido por Gonzalo Sep\u00falveda.<\/p>\n<p data-start=\"424\" data-end=\"675\">La producci\u00f3n fue premiada con el Prix du Film Court Mordant en el festival franc\u00e9s Silence, \u00c7a Touille, un certamen que busca unir el cine con el arte gastron\u00f3mico, reconociendo trabajos que combinan creatividad narrativa y est\u00e9tica visual.<\/p>\n<p data-start=\"677\" data-end=\"1078\">\u201cLa Matadero \u2013 La Carnicer\u00eda\u201d se caracteriza por su atm\u00f3sfera dist\u00f3pica, en la que Melo interpreta a un carnicero que, junto a Pablo Canales, enfrenta las consecuencias de un planeta devastado por el colapso ambiental. La narrativa del cortometraje destaca por su capacidad de generar reflexi\u00f3n sobre el futuro del planeta, mientras mantiene un fuerte componente art\u00edstico y cinematogr\u00e1fico.<\/p>\n<p data-start=\"1080\" data-end=\"1417\">Este reconocimiento internacional no solo reafirma la trayectoria de Pancho Melo como uno de los actores chilenos m\u00e1s destacados de su generaci\u00f3n, sino que tambi\u00e9n pone de relieve el talento local en la escena cinematogr\u00e1fica global, abriendo espacios para la participaci\u00f3n de Chile en festivales de gran relevancia fuera del pa\u00eds.<\/p>\n<p data-start=\"1419\" data-end=\"1648\">Con este logro, Melo contin\u00faa consolidando su carrera y demostrando que el cine chileno puede competir y destacarse a nivel internacional, aportando historias de calidad que combinan profundidad tem\u00e1tica y excelencia art\u00edstica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El actor chileno Pancho Melo suma un nuevo reconocimiento internacional gracias a su participaci\u00f3n en el cortometraje \u201cLa Matadero \u2013 La Carnicer\u00eda\u201d, dirigido por Gonzalo Sep\u00falveda. La producci\u00f3n fue premiada con el Prix du Film Court Mordant en el festival franc\u00e9s Silence, \u00c7a Touille, un certamen que busca unir el cine con el arte gastron\u00f3mico, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2757,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"_links":{"self":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/2756"}],"collection":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2756"}],"version-history":[{"count":1,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/2756\/revisions"}],"predecessor-version":[{"id":2758,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/2756\/revisions\/2758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/media\/2757"}],"wp:attachment":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}