{"id":2838,"date":"2025-09-28T20:50:46","date_gmt":"2025-09-28T23:50:46","guid":{"rendered":"https:\/\/latinaradio.cl\/?p=2838"},"modified":"2025-09-28T20:50:46","modified_gmt":"2025-09-28T23:50:46","slug":"isp-alerta-por-hallazgo-de-drogas-en-adhesivo-con-diseno-infantil","status":"publish","type":"post","link":"https:\/\/latinaradio.cl\/index.php\/2025\/09\/28\/isp-alerta-por-hallazgo-de-drogas-en-adhesivo-con-diseno-infantil\/","title":{"rendered":"ISP alerta por hallazgo de drogas en adhesivo con dise\u00f1o infantil"},"content":{"rendered":"<p data-start=\"138\" data-end=\"409\">El Instituto de Salud P\u00fablica (ISP) emiti\u00f3 una alerta sanitaria luego de detectar por primera vez en Chile una mezcla de drogas il\u00edcitas en un adhesivo, lo que ha generado gran preocupaci\u00f3n por los riesgos que implica, especialmente en ni\u00f1os y adolescentes.<\/p>\n<p data-start=\"411\" data-end=\"640\">Durante una fiscalizaci\u00f3n, se incaut\u00f3 un sticker con dise\u00f1o de cara sonriente, dentro del cual se identificaron coca\u00edna, ketamina y delta-9-tetrahidrocannabinol (THC), el principal compuesto psicoactivo de la marihuana.<\/p>\n<p data-start=\"642\" data-end=\"923\">Seg\u00fan explic\u00f3 Boris Duffau, jefe del Departamento de Salud Ambiental del ISP, \u201ces la primera vez que se detectan estas sustancias en un soporte de este tipo, lo que implica un riesgo significativo, sobre todo para menores que pueden entrar en contacto con ellas sin saberlo\u201d.<\/p>\n<h2 data-start=\"925\" data-end=\"954\">Riesgo para la poblaci\u00f3n<\/h2>\n<p data-start=\"955\" data-end=\"1214\">El uso de un formato gr\u00e1fico y llamativo aumenta la posibilidad de que el producto llegue a manos de ni\u00f1os o adolescentes, quienes podr\u00edan manipularlo sin reconocer que se trata de una droga. Esto eleva el riesgo de exposici\u00f3n accidental e intoxicaci\u00f3n.<\/p>\n<h2 data-start=\"1216\" data-end=\"1244\">Llamado a la prevenci\u00f3n<\/h2>\n<p data-start=\"1245\" data-end=\"1585\">El ISP hizo un llamado a extremar las medidas de cuidado en los hogares y espacios p\u00fablicos, y reiter\u00f3 que este tipo de hallazgos muestran la constante evoluci\u00f3n en las formas de distribuci\u00f3n de drogas il\u00edcitas. Adem\u00e1s, se record\u00f3 a la poblaci\u00f3n que cualquier hallazgo sospechoso debe ser denunciado a las autoridades competentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto de Salud P\u00fablica (ISP) emiti\u00f3 una alerta sanitaria luego de detectar por primera vez en Chile una mezcla de drogas il\u00edcitas en un adhesivo, lo que ha generado gran preocupaci\u00f3n por los riesgos que implica, especialmente en ni\u00f1os y adolescentes. Durante una fiscalizaci\u00f3n, se incaut\u00f3 un sticker con dise\u00f1o de cara sonriente, dentro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2839,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/2838"}],"collection":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2838"}],"version-history":[{"count":1,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/2838\/revisions"}],"predecessor-version":[{"id":2840,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/2838\/revisions\/2840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/media\/2839"}],"wp:attachment":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}