{"id":3027,"date":"2025-10-09T17:15:50","date_gmt":"2025-10-09T20:15:50","guid":{"rendered":"https:\/\/latinaradio.cl\/?p=3027"},"modified":"2025-10-09T17:15:50","modified_gmt":"2025-10-09T20:15:50","slug":"suben-los-combustibles-a-nivel-nacional-diesel-lidera-las-alzas","status":"publish","type":"post","link":"https:\/\/latinaradio.cl\/index.php\/2025\/10\/09\/suben-los-combustibles-a-nivel-nacional-diesel-lidera-las-alzas\/","title":{"rendered":"Suben los combustibles a nivel nacional: di\u00e9sel lidera las alzas"},"content":{"rendered":"<p data-start=\"72\" data-end=\"274\">Desde este jueves 9 de octubre, los precios de los combustibles registran un nuevo aumento en todo el pa\u00eds, seg\u00fan el m\u00e1s reciente informe entregado por la Empresa Nacional del Petr\u00f3leo (ENAP).<\/p>\n<p data-start=\"276\" data-end=\"595\">De acuerdo al reporte, la bencina de 93 octanos sube $7,6 por litro, mientras que la bencina de 97 octanos aumenta $4,6 por litro. En tanto, el di\u00e9sel lidera las alzas con un incremento de $10,3 por litro, y el kerosene (parafina) tambi\u00e9n presenta una fuerte subida de $16,6 por litro.<\/p>\n<p data-start=\"597\" data-end=\"754\">El \u00fanico combustible que registra una baja esta semana es el Gas Licuado de Petr\u00f3leo (GLP) de uso vehicular, con una disminuci\u00f3n de $3,4 por litro.<\/p>\n<p data-start=\"756\" data-end=\"1030\">ENAP record\u00f3 que no regula ni fija los precios de los combustibles en Chile, ya que su rol es \u00fanicamente informativo, en el marco del Mecanismo de Estabilizaci\u00f3n de Precios de los Combustibles (MEPCO), que busca evitar variaciones bruscas en los valores al consumidor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde este jueves 9 de octubre, los precios de los combustibles registran un nuevo aumento en todo el pa\u00eds, seg\u00fan el m\u00e1s reciente informe entregado por la Empresa Nacional del Petr\u00f3leo (ENAP). De acuerdo al reporte, la bencina de 93 octanos sube $7,6 por litro, mientras que la bencina de 97 octanos aumenta $4,6 por [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3028,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/3027"}],"collection":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/comments?post=3027"}],"version-history":[{"count":2,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/3027\/revisions"}],"predecessor-version":[{"id":3030,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/3027\/revisions\/3030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/media\/3028"}],"wp:attachment":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/media?parent=3027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/categories?post=3027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/tags?post=3027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}