{"id":6117,"date":"2026-05-12T23:46:06","date_gmt":"2026-05-13T02:46:06","guid":{"rendered":"https:\/\/latinaradio.cl\/?p=6117"},"modified":"2026-05-12T23:46:06","modified_gmt":"2026-05-13T02:46:06","slug":"rafael-araos-rompe-el-silencio-y-acusa-plan-masivo-de-despidos-en-el-ministerio-de-ciencias","status":"publish","type":"post","link":"https:\/\/latinaradio.cl\/index.php\/2026\/05\/12\/rafael-araos-rompe-el-silencio-y-acusa-plan-masivo-de-despidos-en-el-ministerio-de-ciencias\/","title":{"rendered":"Rafael Araos rompe el silencio y acusa plan masivo de despidos en el Ministerio de Ciencias"},"content":{"rendered":"<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"relative w-full overflow-visible\">\n<section class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-69c341f4-f1d0-83e9-be36-0797751e24a8-11\" data-turn-id-container=\"request-69c341f4-f1d0-83e9-be36-0797751e24a8-11\" data-testid=\"conversation-turn-753\" data-scroll-anchor=\"false\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"bc59bf02-898b-4dd7-8b1a-60b137880e67\" data-message-model-slug=\"gpt-5-5\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full dark markdown-new-styling\">\n<p data-start=\"97\" data-end=\"379\">El exsubsecretario de Ciencias, <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Rafael Araos<\/span><\/span>, entreg\u00f3 nuevos antecedentes sobre su salida del gobierno en una conversaci\u00f3n exclusiva con el periodista <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Daniel Matamala<\/span><\/span> de <a class=\"decorated-link\" href=\"https:\/\/www.chilevision.cl?utm_source=chatgpt.com\" target=\"_new\" rel=\"noopener\" data-start=\"314\" data-end=\"378\">Chilevisi\u00f3n<\/a>.<\/p>\n<p data-start=\"381\" data-end=\"623\">A trav\u00e9s de mensajes, la exautoridad desminti\u00f3 p\u00fablicamente la versi\u00f3n entregada por la ministra <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Ximena Lincolao<\/span><\/span> y asegur\u00f3 que s\u00ed exist\u00eda una instrucci\u00f3n para dise\u00f1ar un plan masivo de despidos al interior de la cartera.<\/p>\n<p data-start=\"625\" data-end=\"834\">\u201cTe puedo confirmar por este medio que la orden de dise\u00f1ar y ejecutar un plan de desvinculaciones masivo es real y hay testigos. Adem\u00e1s, \u00bfpor qu\u00e9 inventar\u00eda yo \u2014o terceros\u2014 algo tan grotesco?\u201d, escribi\u00f3 Araos.<\/p>\n<p data-start=\"836\" data-end=\"989\">El exsubsecretario tambi\u00e9n aclar\u00f3 que esa situaci\u00f3n no fue el \u00fanico motivo que lo llev\u00f3 a dejar el cargo, aunque s\u00ed marc\u00f3 el punto de quiebre definitivo.<\/p>\n<p data-start=\"991\" data-end=\"1171\">\u201c\u00bfFue la \u00fanica raz\u00f3n por la que renunci\u00e9? No, fue la gota que rebals\u00f3 el vaso. \u00bfQu\u00e9 pas\u00f3? Profundas diferencias de fondo y forma acerca de c\u00f3mo enfrentar un mismo desaf\u00edo\u201d, agreg\u00f3.<\/p>\n<p data-start=\"1173\" data-end=\"1405\" data-is-last-node=\"\" data-is-only-node=\"\">Las declaraciones de Araos vuelven a tensionar el escenario al interior del Ministerio de Ciencias, luego de la renuncia de varias autoridades y funcionarios ligados a la cartera en medio de cuestionamientos por recortes y despidos.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\"><\/div>\n<div class=\"mt-3 w-full empty:hidden\">\n<div class=\"text-center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<div class=\"contents\"><\/div>\n<\/div>\n<\/div>\n<div class=\"pointer-events-none -mt-px h-px translate-y-[calc(var(--scroll-root-safe-area-inset-bottom)-14*var(--spacing))]\" aria-hidden=\"true\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El exsubsecretario de Ciencias, Rafael Araos, entreg\u00f3 nuevos antecedentes sobre su salida del gobierno en una conversaci\u00f3n exclusiva con el periodista Daniel Matamala de Chilevisi\u00f3n. A trav\u00e9s de mensajes, la exautoridad desminti\u00f3 p\u00fablicamente la versi\u00f3n entregada por la ministra Ximena Lincolao y asegur\u00f3 que s\u00ed exist\u00eda una instrucci\u00f3n para dise\u00f1ar un plan masivo de despidos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6118,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/6117"}],"collection":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/comments?post=6117"}],"version-history":[{"count":1,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/6117\/revisions"}],"predecessor-version":[{"id":6119,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/posts\/6117\/revisions\/6119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/media\/6118"}],"wp:attachment":[{"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/media?parent=6117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/categories?post=6117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latinaradio.cl\/index.php\/wp-json\/wp\/v2\/tags?post=6117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}